{"id":2318,"date":"2022-06-19T19:55:32","date_gmt":"2022-06-19T17:55:32","guid":{"rendered":"http:\/\/lasmunsweb.test\/carta\/todos\/jamon-queso\/"},"modified":"2026-06-11T15:53:59","modified_gmt":"2026-06-11T13:53:59","slug":"fiambre-e-queijo","status":"publish","type":"productos","link":"https:\/\/lasmuns.com\/pt\/carta\/empanadas-pt\/todos\/fiambre-e-queijo\/","title":{"rendered":"Fiambre e Queijo"},"content":{"rendered":"<!-- template --><div class=\"bcblq bcblq-full-image-text bcblq-opc--derecha\" ><div class=\"container-fluid\" style=\"background-image:url(https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Property-1jamon-2.png)\"><div class=\"row\"><div class=\"col\"><div class=\"bcblq-full-image-text-imagen\" ><div class=\"bcblq-full-image-text-caja\" style=\"background-color:#FFF;\"><h2 style=\"color:primary: Primario;\">A que agrada a todos!<\/h2><p style=\"color:primary: Primario;\">Cubos de fiambre fumado cozido, mozzarella 100% e um toque subtil de azeite extra virgem.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><!-- \/template -->\n\n<!-- template bcblq-carrusel --><div class=\"bcblq bcblq-carrusel   contenedor__full-width usa-fondo\" ><div class=\"container-fluid\" style=\"background-color:#eae7e1\"><div class=\"row bcblq-carrusel-header\"><div class=\"col\"><div class=\"bcblq-half-image-text-titulo_decorativo\">Destacadas<\/div><h2 class=\"bcblq-carrusel-titulo\">Mais op\u00e7\u00f5es Similares<\/h2><a href=\"\/pt\/carta\/empanadas-pt\" class=\"bcblq-carrusel-etiqueta_ver_todos btn btn-flecha\">Ver tudo<span><svg version=\"1.1\" baseProfile=\"basic\" id=\"Layer_1\"\n\t xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewBox=\"0 0 11 22\"\n\t xml:space=\"preserve\">\n<path fill=\"#494240\" d=\"M1.7,21.9c-0.4,0-0.7-0.1-1-0.4C0,21-0.1,20,0.5,19.3L7.2,11L0.5,2.7C-0.1,2,0,1,0.7,0.4C1.4-0.1,2.4,0,3,0.7l7.6,9.3c0.5,0.6,0.5,1.4,0,2L3,21.3C2.6,21.7,2.2,21.9,1.7,21.9z\"\/>\n<\/svg>\n<\/span><\/a><\/div><\/div><div class=\"row bcblq-carrusel-contenido\"><div class=\"col\"><section class=\"bcblq-carrusel-container\"><div class=\"swiper\"><div class=\"custom-loader-wrapper\"><div class=\"custom-loader\"><\/div><\/div><div class=\"swiper-wrapper\"><div class=\"swiper-slide\"><div class=\"col\">\n\t<div class=\"bcblq--card bcblq--card_producto custom-new\">\n\t\t<a href=\"https:\/\/lasmuns.com\/pt\/carta\/empanadas-pt\/todos\/caril-de-frango\/\">\t\t<figure\n\t\t\tclass=\"bcblq--card_imagen\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_PolloAlCurry-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"las muns empanadas argentinas para llevar pollo al curry\" srcset=\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_PolloAlCurry-768x512.jpg 768w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_PolloAlCurry-300x200.jpg 300w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_PolloAlCurry-1024x683.jpg 1024w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_PolloAlCurry.jpg 1501w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\t\t\n\t\t<div class=\"bcblq--card_detalle\">\n\t\t\t<div class=\"bcblq--card_label_boton bcblq__sin-precio\">\n\t\t\t\t<h5>Caril de Frango<\/h5>\n\t\t\t<\/div>\n\t\t\t<div class=\"bcblq--card_descripcion\">Todo o aroma e sabor do sul da \u00cdndia! Suculentos cubos de frango assados, cebolas douradas, mistura de especiarias indianas e cebolinho verde.\n<\/div>\n\t\t<\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n<\/div><div class=\"swiper-slide\"><div class=\"col\">\n\t<div class=\"bcblq--card bcblq--card_producto custom-new\">\n\t\t<a href=\"https:\/\/lasmuns.com\/pt\/carta\/empanadas-pt\/todos\/carne-suave\/\">\t\t<figure\n\t\t\tclass=\"bcblq--card_imagen\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"513\" src=\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_TerneraSuave-768x513.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"las muns empanadas argentinas para llevar ternera suave\" srcset=\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_TerneraSuave-768x513.jpg 768w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_TerneraSuave-300x200.jpg 300w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_TerneraSuave-1024x683.jpg 1024w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_TerneraSuave.jpg 1500w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\t\t\n\t\t<div class=\"bcblq--card_detalle\">\n\t\t\t<div class=\"bcblq--card_label_boton bcblq__sin-precio\">\n\t\t\t\t<h5>Carne Suave<\/h5>\n\t\t\t<\/div>\n\t\t\t<div class=\"bcblq--card_descripcion\">Uma viagem pelo norte da Argentina!\nCubos super tenros de carne, cebolas douradas, ovos cozidos e mistura de especiarias argentinas.<\/div>\n\t\t<\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n<\/div><div class=\"swiper-slide\"><div class=\"col\">\n\t<div class=\"bcblq--card bcblq--card_producto custom-new\">\n\t\t<a href=\"https:\/\/lasmuns.com\/pt\/carta\/empanadas-pt\/todos\/frango-thai\/\">\t\t<figure\n\t\t\tclass=\"bcblq--card_imagen\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"513\" src=\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_PolloThai-768x513.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"las muns empanadas argentinas para llevar pollo thai\" srcset=\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_PolloThai-768x513.jpg 768w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_PolloThai-300x200.jpg 300w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_PolloThai-1024x683.jpg 1024w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_PolloThai.jpg 1500w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\t\t\n\t\t<div class=\"bcblq--card_detalle\">\n\t\t\t<div class=\"bcblq--card_label_boton bcblq__sin-precio\">\n\t\t\t\t<h5>Frango Thai<\/h5>\n\t\t\t<\/div>\n\t\t\t<div class=\"bcblq--card_descripcion\">Aromas e sabores de Bangkok! Suculentos peda\u00e7os de frango salteados com um molho de leite de coco, pasta de caril tailand\u00eas, gengibre e cebolinho. Vai desfazer-se na boca.<\/div>\n\t\t<\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n<\/div><div class=\"swiper-slide\"><div class=\"col\">\n\t<div class=\"bcblq--card bcblq--card_producto custom-new\">\n\t\t<a href=\"https:\/\/lasmuns.com\/pt\/carta\/empanadas-pt\/todos\/carne-picante\/\">\t\t<figure\n\t\t\tclass=\"bcblq--card_imagen\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_TerneraPicante-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"las muns empanadas argentinas para llevar ternera picante\" srcset=\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_TerneraPicante-768x512.jpg 768w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_TerneraPicante-300x200.jpg 300w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_TerneraPicante-1024x683.jpg 1024w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_TerneraPicante.jpg 1501w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\t\t\n\t\t<div class=\"bcblq--card_detalle\">\n\t\t\t<div class=\"bcblq--card_label_boton bcblq__sin-precio\">\n\t\t\t\t<h5>Carne Picante<\/h5>\n\t\t\t<\/div>\n\t\t\t<div class=\"bcblq--card_descripcion\">Alerta picante, prova com cuidado! Cubos super macios de carne, cebolas douradas, ovos cozidos e uma mistura de pimentas mo\u00eddas e fumadas.<\/div>\n\t\t<\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n<\/div><div class=\"swiper-slide\"><div class=\"col\">\n\t<div class=\"bcblq--card bcblq--card_producto custom-new\">\n\t\t<a href=\"https:\/\/lasmuns.com\/pt\/carta\/empanadas-pt\/todos\/atum-galiceiro\/\">\t\t<figure\n\t\t\tclass=\"bcblq--card_imagen\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_Atun-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"las muns empanadas argentinas para llevar\" srcset=\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_Atun-768x512.jpg 768w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_Atun-300x200.jpg 300w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_Atun-1024x683.jpg 1024w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_Atun.jpg 1501w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\t\t\n\t\t<div class=\"bcblq--card_detalle\">\n\t\t\t<div class=\"bcblq--card_label_boton bcblq__sin-precio\">\n\t\t\t\t<h5>Atum a\u0300 Galega<\/h5>\n\t\t\t<\/div>\n\t\t\t<div class=\"bcblq--card_descripcion\">O aroma e sabor a mar! Com um refogado de cebolas, pimentos vermelhos, azeite, tomate natural e deliciosos peda\u00e7os de atum.\n<\/div>\n\t\t<\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n<\/div><div class=\"swiper-slide\"><div class=\"col\">\n\t<div class=\"bcblq--card bcblq--card_producto custom-new\">\n\t\t<a href=\"https:\/\/lasmuns.com\/pt\/carta\/empanadas-pt\/todos\/cheeseburger\/\">\t\t<figure\n\t\t\tclass=\"bcblq--card_imagen\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_Cheeseburger-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"las muns empanadas argentinas veganas cheeseburger\" srcset=\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_Cheeseburger-768x512.jpg 768w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_Cheeseburger-300x200.jpg 300w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_Cheeseburger-1024x683.jpg 1024w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_Cheeseburger.jpg 1501w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\t\t\n\t\t<div class=\"bcblq--card_detalle\">\n\t\t\t<div class=\"bcblq--card_label_boton bcblq__sin-precio\">\n\t\t\t\t<h5>Cheeseburger (vegana)<\/h5>\n\t\t\t<\/div>\n\t\t\t<div class=\"bcblq--card_descripcion\">Uma del\u00edcia! Feita com &#8220;hamb\u00farguer&#8221; de Garden Gourmet (produto vegano) temperada com molho de soja e ervas selecionadas, cebola salteada, queijo cheddar cremoso vegano e cebolinho verde. N\u00e3o vais acreditar neste sabor!<\/div>\n\t\t<\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n<\/div><\/div><\/div><div class=\"swiper-arrows-wrapper bottom-mobile\"><div class=\"swiper-button swiper-button-prev\"><?xml version=\"1.0\" encoding=\"utf-8\"?>\n<!-- Generator: Adobe Illustrator 22.1.0, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n<svg version=\"1.1\" baseProfile=\"basic\" id=\"Layer_1\"\n\t xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewBox=\"0 0 11 22\"\n\t xml:space=\"preserve\">\n<path fill=\"#494240\" d=\"M9.3,0.1c0.4,0,0.7,0.1,1,0.4C11,1,11.1,2,10.5,2.7L3.8,11l6.8,8.3c0.6,0.7,0.5,1.7-0.2,2.3C9.6,22.1,8.6,22,8,21.3L0.5,12c-0.5-0.6-0.5-1.4,0-2L8,0.7C8.4,0.3,8.8,0.1,9.3,0.1z\"\/>\n<\/svg>\n<\/div><div class=\"swiper-button swiper-button-next\"><svg version=\"1.1\" baseProfile=\"basic\" id=\"Layer_1\"\n\t xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewBox=\"0 0 11 22\"\n\t xml:space=\"preserve\">\n<path fill=\"#494240\" d=\"M1.7,21.9c-0.4,0-0.7-0.1-1-0.4C0,21-0.1,20,0.5,19.3L7.2,11L0.5,2.7C-0.1,2,0,1,0.7,0.4C1.4-0.1,2.4,0,3,0.7l7.6,9.3c0.5,0.6,0.5,1.4,0,2L3,21.3C2.6,21.7,2.2,21.9,1.7,21.9z\"\/>\n<\/svg>\n<\/div><\/div><\/section><\/div><\/div><\/div><\/div><!-- \/template -->","protected":false},"excerpt":{"rendered":"<p>A que agrada a todos! Cubos de fiambre fumado cozido, mozzarella 100% e um toque subtil de azeite extra virgem.<\/p>\n","protected":false},"featured_media":0,"menu_order":1,"template":"","tipos":[67],"class_list":["post-2318","productos","type-productos","status-publish","hentry","tipos-empanadas-pt"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiambre e Queijo - Las Muns<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasmuns.com\/pt\/carta\/empanadas-pt\/todos\/fiambre-e-queijo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiambre e Queijo - Las Muns\" \/>\n<meta property=\"og:description\" content=\"A que agrada a todos! Cubos de fiambre fumado cozido, mozzarella 100% e um toque subtil de azeite extra virgem.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasmuns.com\/pt\/carta\/empanadas-pt\/todos\/fiambre-e-queijo\/\" \/>\n<meta property=\"og:site_name\" content=\"Las Muns\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-11T13:53:59+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lasmuns.com\/pt\/carta\/empanadas-pt\/todos\/fiambre-e-queijo\/\",\"url\":\"https:\/\/lasmuns.com\/pt\/carta\/empanadas-pt\/todos\/fiambre-e-queijo\/\",\"name\":\"Fiambre e Queijo - Las Muns\",\"isPartOf\":{\"@id\":\"https:\/\/lasmuns.com\/pt\/#website\"},\"datePublished\":\"2022-06-19T17:55:32+00:00\",\"dateModified\":\"2026-06-11T13:53:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/lasmuns.com\/pt\/carta\/empanadas-pt\/todos\/fiambre-e-queijo\/#breadcrumb\"},\"inLanguage\":\"pt\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lasmuns.com\/pt\/carta\/empanadas-pt\/todos\/fiambre-e-queijo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lasmuns.com\/pt\/carta\/empanadas-pt\/todos\/fiambre-e-queijo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/lasmuns.com\/pt\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\/\/lasmuns.com\/pt\/carta\/%tipo%\/%subtipo%\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fiambre e Queijo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lasmuns.com\/pt\/#website\",\"url\":\"https:\/\/lasmuns.com\/pt\/\",\"name\":\"Las Muns\",\"description\":\"The &#039;Heart-Made&#039; Empanada\",\"publisher\":{\"@id\":\"https:\/\/lasmuns.com\/pt\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lasmuns.com\/pt\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/lasmuns.com\/pt\/#organization\",\"name\":\"Las Muns\",\"url\":\"https:\/\/lasmuns.com\/pt\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt\",\"@id\":\"https:\/\/lasmuns.com\/pt\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/isologo-slogan2.svg\",\"contentUrl\":\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/isologo-slogan2.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"Las Muns\"},\"image\":{\"@id\":\"https:\/\/lasmuns.com\/pt\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/lasmuns\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiambre e Queijo - Las Muns","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasmuns.com\/pt\/carta\/empanadas-pt\/todos\/fiambre-e-queijo\/","og_locale":"pt_PT","og_type":"article","og_title":"Fiambre e Queijo - Las Muns","og_description":"A que agrada a todos! Cubos de fiambre fumado cozido, mozzarella 100% e um toque subtil de azeite extra virgem.","og_url":"https:\/\/lasmuns.com\/pt\/carta\/empanadas-pt\/todos\/fiambre-e-queijo\/","og_site_name":"Las Muns","article_modified_time":"2026-06-11T13:53:59+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lasmuns.com\/pt\/carta\/empanadas-pt\/todos\/fiambre-e-queijo\/","url":"https:\/\/lasmuns.com\/pt\/carta\/empanadas-pt\/todos\/fiambre-e-queijo\/","name":"Fiambre e Queijo - Las Muns","isPartOf":{"@id":"https:\/\/lasmuns.com\/pt\/#website"},"datePublished":"2022-06-19T17:55:32+00:00","dateModified":"2026-06-11T13:53:59+00:00","breadcrumb":{"@id":"https:\/\/lasmuns.com\/pt\/carta\/empanadas-pt\/todos\/fiambre-e-queijo\/#breadcrumb"},"inLanguage":"pt","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasmuns.com\/pt\/carta\/empanadas-pt\/todos\/fiambre-e-queijo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lasmuns.com\/pt\/carta\/empanadas-pt\/todos\/fiambre-e-queijo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lasmuns.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/lasmuns.com\/pt\/carta\/%tipo%\/%subtipo%\/"},{"@type":"ListItem","position":3,"name":"Fiambre e Queijo"}]},{"@type":"WebSite","@id":"https:\/\/lasmuns.com\/pt\/#website","url":"https:\/\/lasmuns.com\/pt\/","name":"Las Muns","description":"The &#039;Heart-Made&#039; Empanada","publisher":{"@id":"https:\/\/lasmuns.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasmuns.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt"},{"@type":"Organization","@id":"https:\/\/lasmuns.com\/pt\/#organization","name":"Las Muns","url":"https:\/\/lasmuns.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"pt","@id":"https:\/\/lasmuns.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/isologo-slogan2.svg","contentUrl":"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/isologo-slogan2.svg","width":"1024","height":"1024","caption":"Las Muns"},"image":{"@id":"https:\/\/lasmuns.com\/pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/lasmuns"]}]}},"_links":{"self":[{"href":"https:\/\/lasmuns.com\/pt\/wp-json\/wp\/v2\/productos\/2318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasmuns.com\/pt\/wp-json\/wp\/v2\/productos"}],"about":[{"href":"https:\/\/lasmuns.com\/pt\/wp-json\/wp\/v2\/types\/productos"}],"wp:attachment":[{"href":"https:\/\/lasmuns.com\/pt\/wp-json\/wp\/v2\/media?parent=2318"}],"wp:term":[{"taxonomy":"tipos","embeddable":true,"href":"https:\/\/lasmuns.com\/pt\/wp-json\/wp\/v2\/tipos?post=2318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}