{"id":3681,"date":"2022-06-17T04:29:11","date_gmt":"2022-06-17T02:29:11","guid":{"rendered":"https:\/\/lasmuns.com\/carta\/todos\/pollo-al-curry\/"},"modified":"2026-06-11T16:28:44","modified_gmt":"2026-06-11T14:28:44","slug":"pollo-al-curry","status":"publish","type":"productos","link":"https:\/\/lasmuns.com\/it\/carta\/empanadas-it\/todos\/pollo-al-curry\/","title":{"rendered":"Pollo al Curry"},"content":{"rendered":"<!-- template --><div class=\"bcblq bcblq-full-image-text bcblq-opc--derecha\" ><div class=\"container-fluid\" style=\"background-image:url(https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Property-1pollo-1.png)\"><div class=\"row\"><div class=\"col\"><div class=\"bcblq-full-image-text-imagen\" ><div class=\"bcblq-full-image-text-caja\" style=\"background-color:#FFF;\"><h2 style=\"color:primary: Primario;\">Tutto l&#8217;aroma del sud dell&#8217;India.<\/h2><p style=\"color:primary: Primario;\">Succoso pollo cotto al forno con spezie indiane, cipolla dorata e erba cipollina. <\/p><\/div><\/div><\/div><\/div><\/div><\/div><!-- \/template -->\n\n<!-- template bcblq-carrusel --><div class=\"bcblq bcblq-carrusel   contenedor__full-width usa-fondo\" ><div class=\"container-fluid\" style=\"background-color:#eae7e1\"><div class=\"row bcblq-carrusel-header\"><div class=\"col\"><div class=\"bcblq-half-image-text-titulo_decorativo\">IN EVIDENZA<\/div><h2 class=\"bcblq-carrusel-titulo\">Pi\u00f9 opzioni simili<\/h2><a href=\"\/carta\/empanadas\" class=\"bcblq-carrusel-etiqueta_ver_todos btn btn-flecha\">Vederlo tutto<span><svg version=\"1.1\" baseProfile=\"basic\" id=\"Layer_1\"\n\t xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewBox=\"0 0 11 22\"\n\t xml:space=\"preserve\">\n<path fill=\"#494240\" d=\"M1.7,21.9c-0.4,0-0.7-0.1-1-0.4C0,21-0.1,20,0.5,19.3L7.2,11L0.5,2.7C-0.1,2,0,1,0.7,0.4C1.4-0.1,2.4,0,3,0.7l7.6,9.3c0.5,0.6,0.5,1.4,0,2L3,21.3C2.6,21.7,2.2,21.9,1.7,21.9z\"\/>\n<\/svg>\n<\/span><\/a><\/div><\/div><div class=\"row bcblq-carrusel-contenido\"><div class=\"col\"><section class=\"bcblq-carrusel-container\"><div class=\"swiper\"><div class=\"custom-loader-wrapper\"><div class=\"custom-loader\"><\/div><\/div><div class=\"swiper-wrapper\"><div class=\"swiper-slide\"><div class=\"col\">\n\t<div class=\"bcblq--card bcblq--card_producto custom-new\">\n\t\t<a href=\"https:\/\/lasmuns.com\/carta\/empanadas\/todos\/jamon-queso\/\">\t\t<figure\n\t\t\tclass=\"bcblq--card_imagen\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"513\" src=\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_JamonyQueso-768x513.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"las muns empanadas argentinas para llevar jam\u00f3n y queso\" srcset=\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_JamonyQueso-768x513.jpg 768w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_JamonyQueso-300x200.jpg 300w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_JamonyQueso-1024x683.jpg 1024w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_JamonyQueso.jpg 1500w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\t\t\n\t\t<div class=\"bcblq--card_detalle\">\n\t\t\t<div class=\"bcblq--card_label_boton bcblq__sin-precio\">\n\t\t\t\t<h5>Jam\u00f3n y Queso<\/h5>\n\t\t\t<\/div>\n\t\t\t<div class=\"bcblq--card_descripcion\">El cl\u00e1sico que amamos: jam\u00f3n cocido ahumado, mozzarella 100% y un toque sutil de AOVE. \u00a1Simplemente perfecta!<\/div>\n\t\t<\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n<\/div><div class=\"swiper-slide\"><div class=\"col\">\n\t<div class=\"bcblq--card bcblq--card_producto custom-new\">\n\t\t<a href=\"https:\/\/lasmuns.com\/it\/carta\/empanadas-it\/todos\/carne-classica\/\">\t\t<figure\n\t\t\tclass=\"bcblq--card_imagen\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"513\" src=\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_TerneraSuave-768x513.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"las muns empanadas argentinas para llevar ternera suave\" srcset=\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_TerneraSuave-768x513.jpg 768w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_TerneraSuave-300x200.jpg 300w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_TerneraSuave-1024x683.jpg 1024w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_TerneraSuave.jpg 1500w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\t\t\n\t\t<div class=\"bcblq--card_detalle\">\n\t\t\t<div class=\"bcblq--card_label_boton bcblq__sin-precio\">\n\t\t\t\t<h5>Manzo<\/h5>\n\t\t\t<\/div>\n\t\t\t<div class=\"bcblq--card_descripcion\">Teneri cubetti di manzo, cipolle dorate, uovo sodo e mix di spezie. L&#8217;autentico sapore del nord argentino!<\/div>\n\t\t<\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n<\/div><div class=\"swiper-slide\"><div class=\"col\">\n\t<div class=\"bcblq--card bcblq--card_producto custom-new\">\n\t\t<a href=\"https:\/\/lasmuns.com\/it\/carta\/empanadas-it\/todos\/pollo-thai\/\">\t\t<figure\n\t\t\tclass=\"bcblq--card_imagen\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Fotos_Muns_PolloThai-768x512.png\" class=\"attachment-medium_large size-medium_large\" alt=\"las muns comida para llevar empanadas de colores take away pollo thai\" srcset=\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Fotos_Muns_PolloThai-768x512.png 768w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Fotos_Muns_PolloThai-300x200.png 300w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Fotos_Muns_PolloThai-1024x682.png 1024w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Fotos_Muns_PolloThai-1536x1024.png 1536w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Fotos_Muns_PolloThai.png 1613w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\t\t\n\t\t<div class=\"bcblq--card_detalle\">\n\t\t\t<div class=\"bcblq--card_label_boton bcblq__sin-precio\">\n\t\t\t\t<h5>Pollo Thai<\/h5>\n\t\t\t<\/div>\n\t\t\t<div class=\"bcblq--card_descripcion\">Succoso pollo in salsa di latte di cocco e curry Thai, con zenzero e erba cipollina. Aromi di Bangkok che si sciolgono in bocca.<\/div>\n\t\t<\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n<\/div><div class=\"swiper-slide\"><div class=\"col\">\n\t<div class=\"bcblq--card bcblq--card_producto custom-new\">\n\t\t<a href=\"https:\/\/lasmuns.com\/carta\/empanadas\/todos\/ternera-picante\/\">\t\t<figure\n\t\t\tclass=\"bcblq--card_imagen\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_TerneraPicante-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"las muns empanadas argentinas para llevar ternera picante\" srcset=\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_TerneraPicante-768x512.jpg 768w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_TerneraPicante-300x200.jpg 300w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_TerneraPicante-1024x683.jpg 1024w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_TerneraPicante.jpg 1501w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\t\t\n\t\t<div class=\"bcblq--card_detalle\">\n\t\t\t<div class=\"bcblq--card_label_boton bcblq__sin-precio\">\n\t\t\t\t<h5>Ternera Picante<\/h5>\n\t\t\t<\/div>\n\t\t\t<div class=\"bcblq--card_descripcion\">Cubos tiernos de ternera, cebolla dorada y huevo cocido, con aj\u00edes molidos y ahumados. Picor justo y adictivo.<\/div>\n\t\t<\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n<\/div><div class=\"swiper-slide\"><div class=\"col\">\n\t<div class=\"bcblq--card bcblq--card_producto custom-new\">\n\t\t<a href=\"https:\/\/lasmuns.com\/carta\/empanadas\/todos\/atun-a-la-gallega\/\">\t\t<figure\n\t\t\tclass=\"bcblq--card_imagen\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_Atun-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"las muns empanadas argentinas para llevar\" srcset=\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_Atun-768x512.jpg 768w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_Atun-300x200.jpg 300w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_Atun-1024x683.jpg 1024w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_Atun.jpg 1501w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\t\t\n\t\t<div class=\"bcblq--card_detalle\">\n\t\t\t<div class=\"bcblq--card_label_boton bcblq__sin-precio\">\n\t\t\t\t<h5>At\u00fan a la Gallega<\/h5>\n\t\t\t<\/div>\n\t\t\t<div class=\"bcblq--card_descripcion\">Sofrito de cebolla y pimientos rojos, tomate natural y exquisito at\u00fan. \u00a1Todo el aroma y sabor del mar gallego!<\/div>\n\t\t<\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n<\/div><div class=\"swiper-slide\"><div class=\"col\">\n\t<div class=\"bcblq--card bcblq--card_producto custom-new\">\n\t\t<a href=\"https:\/\/lasmuns.com\/carta\/empanadas\/todos\/cheeseburger\/\">\t\t<figure\n\t\t\tclass=\"bcblq--card_imagen\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_Cheeseburger-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"las muns empanadas argentinas veganas cheeseburger\" srcset=\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_Cheeseburger-768x512.jpg 768w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_Cheeseburger-300x200.jpg 300w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_Cheeseburger-1024x683.jpg 1024w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_Cheeseburger.jpg 1501w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\t\t\n\t\t<div class=\"bcblq--card_detalle\">\n\t\t\t<div class=\"bcblq--card_label_boton bcblq__sin-precio\">\n\t\t\t\t<h5>Cheeseburger (vegana)<\/h5>\n\t\t\t<\/div>\n\t\t\t<div class=\"bcblq--card_descripcion\">Burger vegana sazonada, cebollas salteadas, cremoso cheddar vegano y un toque de ciboulette. \u00a1No podr\u00e1s creer que es vegana!<\/div>\n\t\t<\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n<\/div><\/div><\/div><div class=\"swiper-arrows-wrapper bottom-mobile\"><div class=\"swiper-button swiper-button-prev\"><?xml version=\"1.0\" encoding=\"utf-8\"?>\n<!-- Generator: Adobe Illustrator 22.1.0, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n<svg version=\"1.1\" baseProfile=\"basic\" id=\"Layer_1\"\n\t xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewBox=\"0 0 11 22\"\n\t xml:space=\"preserve\">\n<path fill=\"#494240\" d=\"M9.3,0.1c0.4,0,0.7,0.1,1,0.4C11,1,11.1,2,10.5,2.7L3.8,11l6.8,8.3c0.6,0.7,0.5,1.7-0.2,2.3C9.6,22.1,8.6,22,8,21.3L0.5,12c-0.5-0.6-0.5-1.4,0-2L8,0.7C8.4,0.3,8.8,0.1,9.3,0.1z\"\/>\n<\/svg>\n<\/div><div class=\"swiper-button swiper-button-next\"><svg version=\"1.1\" baseProfile=\"basic\" id=\"Layer_1\"\n\t xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewBox=\"0 0 11 22\"\n\t xml:space=\"preserve\">\n<path fill=\"#494240\" d=\"M1.7,21.9c-0.4,0-0.7-0.1-1-0.4C0,21-0.1,20,0.5,19.3L7.2,11L0.5,2.7C-0.1,2,0,1,0.7,0.4C1.4-0.1,2.4,0,3,0.7l7.6,9.3c0.5,0.6,0.5,1.4,0,2L3,21.3C2.6,21.7,2.2,21.9,1.7,21.9z\"\/>\n<\/svg>\n<\/div><\/div><\/section><\/div><\/div><\/div><\/div><!-- \/template -->","protected":false},"excerpt":{"rendered":"<p>Succoso pollo cotto al forno con spezie indiane, cipolla dorata e erba cipollina. Tutto l&#8217;aroma del sud dell&#8217;India.<\/p>\n","protected":false},"featured_media":0,"menu_order":9,"template":"","tipos":[171],"class_list":["post-3681","productos","type-productos","status-publish","hentry","tipos-empanadas-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pollo al Curry - Las Muns<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasmuns.com\/it\/carta\/empanadas-it\/todos\/pollo-al-curry\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pollo al Curry - Las Muns\" \/>\n<meta property=\"og:description\" content=\"Succoso pollo cotto al forno con spezie indiane, cipolla dorata e erba cipollina. Tutto l&#039;aroma del sud dell&#039;India.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasmuns.com\/it\/carta\/empanadas-it\/todos\/pollo-al-curry\/\" \/>\n<meta property=\"og:site_name\" content=\"Las Muns\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-11T14:28:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lasmuns.com\/it\/carta\/empanadas-it\/todos\/pollo-al-curry\/\",\"url\":\"https:\/\/lasmuns.com\/it\/carta\/empanadas-it\/todos\/pollo-al-curry\/\",\"name\":\"Pollo al Curry - Las Muns\",\"isPartOf\":{\"@id\":\"https:\/\/lasmuns.com\/it\/#website\"},\"datePublished\":\"2022-06-17T02:29:11+00:00\",\"dateModified\":\"2026-06-11T14:28:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/lasmuns.com\/it\/carta\/empanadas-it\/todos\/pollo-al-curry\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lasmuns.com\/it\/carta\/empanadas-it\/todos\/pollo-al-curry\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lasmuns.com\/it\/carta\/empanadas-it\/todos\/pollo-al-curry\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/lasmuns.com\/it\/pagina-ejemplo\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\/\/lasmuns.com\/it\/carta\/%tipo%\/%subtipo%\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pollo al Curry\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lasmuns.com\/it\/#website\",\"url\":\"https:\/\/lasmuns.com\/it\/\",\"name\":\"Las Muns\",\"description\":\"The &#039;Heart-Made&#039; Empanada\",\"publisher\":{\"@id\":\"https:\/\/lasmuns.com\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lasmuns.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/lasmuns.com\/it\/#organization\",\"name\":\"Las Muns\",\"url\":\"https:\/\/lasmuns.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/lasmuns.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/isologo-slogan2.svg\",\"contentUrl\":\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/isologo-slogan2.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"Las Muns\"},\"image\":{\"@id\":\"https:\/\/lasmuns.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/lasmuns\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pollo al Curry - Las Muns","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasmuns.com\/it\/carta\/empanadas-it\/todos\/pollo-al-curry\/","og_locale":"it_IT","og_type":"article","og_title":"Pollo al Curry - Las Muns","og_description":"Succoso pollo cotto al forno con spezie indiane, cipolla dorata e erba cipollina. Tutto l'aroma del sud dell'India.","og_url":"https:\/\/lasmuns.com\/it\/carta\/empanadas-it\/todos\/pollo-al-curry\/","og_site_name":"Las Muns","article_modified_time":"2026-06-11T14:28:44+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lasmuns.com\/it\/carta\/empanadas-it\/todos\/pollo-al-curry\/","url":"https:\/\/lasmuns.com\/it\/carta\/empanadas-it\/todos\/pollo-al-curry\/","name":"Pollo al Curry - Las Muns","isPartOf":{"@id":"https:\/\/lasmuns.com\/it\/#website"},"datePublished":"2022-06-17T02:29:11+00:00","dateModified":"2026-06-11T14:28:44+00:00","breadcrumb":{"@id":"https:\/\/lasmuns.com\/it\/carta\/empanadas-it\/todos\/pollo-al-curry\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasmuns.com\/it\/carta\/empanadas-it\/todos\/pollo-al-curry\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lasmuns.com\/it\/carta\/empanadas-it\/todos\/pollo-al-curry\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lasmuns.com\/it\/pagina-ejemplo\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/lasmuns.com\/it\/carta\/%tipo%\/%subtipo%\/"},{"@type":"ListItem","position":3,"name":"Pollo al Curry"}]},{"@type":"WebSite","@id":"https:\/\/lasmuns.com\/it\/#website","url":"https:\/\/lasmuns.com\/it\/","name":"Las Muns","description":"The &#039;Heart-Made&#039; Empanada","publisher":{"@id":"https:\/\/lasmuns.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasmuns.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/lasmuns.com\/it\/#organization","name":"Las Muns","url":"https:\/\/lasmuns.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/lasmuns.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/isologo-slogan2.svg","contentUrl":"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/isologo-slogan2.svg","width":"1024","height":"1024","caption":"Las Muns"},"image":{"@id":"https:\/\/lasmuns.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/lasmuns"]}]}},"_links":{"self":[{"href":"https:\/\/lasmuns.com\/it\/wp-json\/wp\/v2\/productos\/3681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasmuns.com\/it\/wp-json\/wp\/v2\/productos"}],"about":[{"href":"https:\/\/lasmuns.com\/it\/wp-json\/wp\/v2\/types\/productos"}],"wp:attachment":[{"href":"https:\/\/lasmuns.com\/it\/wp-json\/wp\/v2\/media?parent=3681"}],"wp:term":[{"taxonomy":"tipos","embeddable":true,"href":"https:\/\/lasmuns.com\/it\/wp-json\/wp\/v2\/tipos?post=3681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}