{"id":3167,"date":"2022-07-04T13:09:37","date_gmt":"2022-07-04T11:09:37","guid":{"rendered":"https:\/\/lasmuns.com\/carta\/todos\/tomate-seco-y-provolone\/"},"modified":"2026-06-11T15:37:39","modified_gmt":"2026-06-11T13:37:39","slug":"tomaquet-sec-provolone","status":"publish","type":"productos","link":"https:\/\/lasmuns.com\/ca\/carta\/empanades-ca\/todos\/tomaquet-sec-provolone\/","title":{"rendered":"Tom\u00e0quet Sec Provolone"},"content":{"rendered":"<!-- template --><div class=\"bcblq bcblq-full-image-text bcblq-opc--derecha\" ><div class=\"container-fluid\" style=\"background-image:url(https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Property-1Tomate-seco-y-Provolone.png)\"><div class=\"row\"><div class=\"col\"><div class=\"bcblq-full-image-text-imagen\" ><div class=\"bcblq-full-image-text-caja\" style=\"background-color:#FFF;\"><h2 style=\"color:primary: Primario;\">El sabor de la bella It\u00e0lia.<\/h2><p style=\"color:primary: Primario;\">Tom\u00e0quets semisecs italians, provolone D.O.P., mozzarella 100% i orenga.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><!-- \/template -->\n\n<!-- template bcblq-carrusel --><div class=\"bcblq bcblq-carrusel   contenedor__full-width usa-fondo\" ><div class=\"container-fluid\" style=\"background-color:#eae7e1\"><div class=\"row bcblq-carrusel-header\"><div class=\"col\"><div class=\"bcblq-half-image-text-titulo_decorativo\">ACOMPANYA<\/div><h2 class=\"bcblq-carrusel-titulo\">M\u00e9s opcions vegetals<\/h2><a href=\"\/carta\/empanadas\" class=\"bcblq-carrusel-etiqueta_ver_todos btn btn-flecha\">Veure-ho tot<span><svg version=\"1.1\" baseProfile=\"basic\" id=\"Layer_1\"\n\t xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewBox=\"0 0 11 22\"\n\t xml:space=\"preserve\">\n<path fill=\"#494240\" d=\"M1.7,21.9c-0.4,0-0.7-0.1-1-0.4C0,21-0.1,20,0.5,19.3L7.2,11L0.5,2.7C-0.1,2,0,1,0.7,0.4C1.4-0.1,2.4,0,3,0.7l7.6,9.3c0.5,0.6,0.5,1.4,0,2L3,21.3C2.6,21.7,2.2,21.9,1.7,21.9z\"\/>\n<\/svg>\n<\/span><\/a><\/div><\/div><div class=\"row bcblq-carrusel-contenido\"><div class=\"col\"><section class=\"bcblq-carrusel-container\"><div class=\"swiper\"><div class=\"custom-loader-wrapper\"><div class=\"custom-loader\"><\/div><\/div><div class=\"swiper-wrapper\"><div class=\"swiper-slide\"><div class=\"col\">\n\t<div class=\"bcblq--card bcblq--card_producto custom-new\">\n\t\t<a href=\"https:\/\/lasmuns.com\/ca\/carta\/empanades-ca\/todos\/bolets-camembert\/\">\t\t<figure\n\t\t\tclass=\"bcblq--card_imagen\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_SetasCamembert-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"las muns empanadas argentinas setas camembert\" srcset=\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_SetasCamembert-768x512.jpg 768w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_SetasCamembert-300x200.jpg 300w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_SetasCamembert-1024x683.jpg 1024w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/07\/Muns_SetasCamembert.jpg 1501w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\t\t\n\t\t<div class=\"bcblq--card_detalle\">\n\t\t\t<div class=\"bcblq--card_label_boton bcblq__sin-precio\">\n\t\t\t\t<h5>Bolets Camembert<\/h5>\n\t\t\t<\/div>\n\t\t\t<div class=\"bcblq--card_descripcion\">Mix de bolets, formatge camembert fos, mozzarella, esp\u00e8cies arom\u00e0tiques i ciboulet. Una barreja de sabors i textures del bosc.<\/div>\n\t\t<\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n<\/div><div class=\"swiper-slide\"><div class=\"col\">\n\t<div class=\"bcblq--card bcblq--card_producto custom-new\">\n\t\t<a href=\"https:\/\/lasmuns.com\/ca\/carta\/empanades-ca\/todos\/formatge-de-cabra\/\">\t\t<figure\n\t\t\tclass=\"bcblq--card_imagen\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"513\" src=\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_CebollaCaramelizada-768x513.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"las muns empanadas argentinas para llevar cebolla caramelizada queso de cabra y nuez\" srcset=\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_CebollaCaramelizada-768x513.jpg 768w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_CebollaCaramelizada-300x200.jpg 300w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_CebollaCaramelizada-1024x683.jpg 1024w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_CebollaCaramelizada.jpg 1500w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\t\t\n\t\t<div class=\"bcblq--card_detalle\">\n\t\t\t<div class=\"bcblq--card_label_boton bcblq__sin-precio\">\n\t\t\t\t<h5>Formatge de Cabra, Nous i Ceba\ufffc<\/h5>\n\t\t\t<\/div>\n\t\t\t<div class=\"bcblq--card_descripcion\">Cebes caramel\u00b7litzades en cocci\u00f3 lenta, formatge rulo de cabra 100% i trossos de nou que fan crunch. La combinaci\u00f3 perfecta!<\/div>\n\t\t<\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n<\/div><div class=\"swiper-slide\"><div class=\"col\">\n\t<div class=\"bcblq--card bcblq--card_producto custom-new\">\n\t\t<a href=\"https:\/\/lasmuns.com\/ca\/carta\/empanades-ca\/todos\/tomaquet-alfabrega-mozzarella\/\">\t\t<figure\n\t\t\tclass=\"bcblq--card_imagen\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_TomateAlbahaca-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"las muns empanadas argentinas para llevar tomate albahaca mozzarella caprese\" srcset=\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_TomateAlbahaca-768x512.jpg 768w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_TomateAlbahaca-300x200.jpg 300w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_TomateAlbahaca-1024x683.jpg 1024w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_TomateAlbahaca.jpg 1501w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\t\t\n\t\t<div class=\"bcblq--card_detalle\">\n\t\t\t<div class=\"bcblq--card_label_boton bcblq__sin-precio\">\n\t\t\t\t<h5>Tom\u00e0quet Alf\u00e0brega Mozzarella\ufffc<\/h5>\n\t\t\t<\/div>\n\t\t\t<div class=\"bcblq--card_descripcion\">Cubs de tom\u00e0quet, pesto d&#8217;alf\u00e0brega fet al nostre obrador, mozzarella 100% i oli d&#8217;oliva verge extra. Una explosi\u00f3 d&#8217;aroma i frescor!<\/div>\n\t\t<\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n<\/div><div class=\"swiper-slide\"><div class=\"col\">\n\t<div class=\"bcblq--card bcblq--card_producto custom-new\">\n\t\t<a href=\"https:\/\/lasmuns.com\/carta\/empanadas\/todos\/olivada-mozzarella\/\">\t\t<figure\n\t\t\tclass=\"bcblq--card_imagen\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"513\" src=\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_MozzarellaOlivada-768x513.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"las muns empanadas de autor argentinas para llevar\" srcset=\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_MozzarellaOlivada-768x513.jpg 768w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_MozzarellaOlivada-300x200.jpg 300w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_MozzarellaOlivada-1024x683.jpg 1024w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_MozzarellaOlivada.jpg 1500w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\t\t\n\t\t<div class=\"bcblq--card_detalle\">\n\t\t\t<div class=\"bcblq--card_label_boton bcblq__sin-precio\">\n\t\t\t\t<h5>Olivada Mozzarella<\/h5>\n\t\t\t<\/div>\n\t\t\t<div class=\"bcblq--card_descripcion\">Trozos de olivas verdes del Mediterr\u00e1neo, mozzarella fundida y huevo cocido. \u00a1Una mezcla adictiva con AOVE!<\/div>\n\t\t<\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n<\/div><div class=\"swiper-slide\"><div class=\"col\">\n\t<div class=\"bcblq--card bcblq--card_producto custom-new\">\n\t\t<a href=\"https:\/\/lasmuns.com\/carta\/empanadas\/todos\/espinacas-emmental\/\">\t\t<figure\n\t\t\tclass=\"bcblq--card_imagen\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_EspinacaEmmental-768x512.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"las muns empanadas argentinas para llevar\" srcset=\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_EspinacaEmmental-768x512.jpg 768w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_EspinacaEmmental-300x200.jpg 300w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_EspinacaEmmental-1024x683.jpg 1024w, https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/Muns_EspinacaEmmental.jpg 1501w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\t\t\n\t\t<div class=\"bcblq--card_detalle\">\n\t\t\t<div class=\"bcblq--card_label_boton bcblq__sin-precio\">\n\t\t\t\t<h5>Espinacas Emmental<\/h5>\n\t\t\t<\/div>\n\t\t\t<div class=\"bcblq--card_descripcion\">Hojas frescas de espinacas, cebollas doradas y una cremosa bechamel con queso emmental. El sabor de la infancia.<\/div>\n\t\t<\/div>\n\n\t\t<\/a>\t<\/div>\n<\/div>\n<\/div><\/div><\/div><div class=\"swiper-arrows-wrapper bottom-mobile\"><div class=\"swiper-button swiper-button-prev\"><?xml version=\"1.0\" encoding=\"utf-8\"?>\n<!-- Generator: Adobe Illustrator 22.1.0, SVG Export Plug-In . SVG Version: 6.00 Build 0)  -->\n<svg version=\"1.1\" baseProfile=\"basic\" id=\"Layer_1\"\n\t xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewBox=\"0 0 11 22\"\n\t xml:space=\"preserve\">\n<path fill=\"#494240\" d=\"M9.3,0.1c0.4,0,0.7,0.1,1,0.4C11,1,11.1,2,10.5,2.7L3.8,11l6.8,8.3c0.6,0.7,0.5,1.7-0.2,2.3C9.6,22.1,8.6,22,8,21.3L0.5,12c-0.5-0.6-0.5-1.4,0-2L8,0.7C8.4,0.3,8.8,0.1,9.3,0.1z\"\/>\n<\/svg>\n<\/div><div class=\"swiper-button swiper-button-next\"><svg version=\"1.1\" baseProfile=\"basic\" id=\"Layer_1\"\n\t xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewBox=\"0 0 11 22\"\n\t xml:space=\"preserve\">\n<path fill=\"#494240\" d=\"M1.7,21.9c-0.4,0-0.7-0.1-1-0.4C0,21-0.1,20,0.5,19.3L7.2,11L0.5,2.7C-0.1,2,0,1,0.7,0.4C1.4-0.1,2.4,0,3,0.7l7.6,9.3c0.5,0.6,0.5,1.4,0,2L3,21.3C2.6,21.7,2.2,21.9,1.7,21.9z\"\/>\n<\/svg>\n<\/div><\/div><\/section><\/div><\/div><\/div><\/div><!-- \/template -->","protected":false},"excerpt":{"rendered":"<p>Tom\u00e0quets semisecs italians, provolone D.O.P., mozzarella 100% i orenga. El sabor de la bella It\u00e0lia.<\/p>\n","protected":false},"featured_media":0,"menu_order":10,"template":"","tipos":[85],"class_list":["post-3167","productos","type-productos","status-publish","hentry","tipos-empanades-ca"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tom\u00e0quet Sec Provolone - Las Muns<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasmuns.com\/ca\/carta\/empanades-ca\/todos\/tomaquet-sec-provolone\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tom\u00e0quet Sec Provolone - Las Muns\" \/>\n<meta property=\"og:description\" content=\"Tom\u00e0quets semisecs italians, provolone D.O.P., mozzarella 100% i orenga. El sabor de la bella It\u00e0lia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasmuns.com\/ca\/carta\/empanades-ca\/todos\/tomaquet-sec-provolone\/\" \/>\n<meta property=\"og:site_name\" content=\"Las Muns\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-11T13:37:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lasmuns.com\/ca\/carta\/empanades-ca\/todos\/tomaquet-sec-provolone\/\",\"url\":\"https:\/\/lasmuns.com\/ca\/carta\/empanades-ca\/todos\/tomaquet-sec-provolone\/\",\"name\":\"Tom\u00e0quet Sec Provolone - Las Muns\",\"isPartOf\":{\"@id\":\"https:\/\/lasmuns.com\/ca\/#website\"},\"datePublished\":\"2022-07-04T11:09:37+00:00\",\"dateModified\":\"2026-06-11T13:37:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/lasmuns.com\/ca\/carta\/empanades-ca\/todos\/tomaquet-sec-provolone\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lasmuns.com\/ca\/carta\/empanades-ca\/todos\/tomaquet-sec-provolone\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lasmuns.com\/ca\/carta\/empanades-ca\/todos\/tomaquet-sec-provolone\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/lasmuns.com\/ca\/pagina-ejemplo\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\/\/lasmuns.com\/ca\/carta\/%tipo%\/%subtipo%\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tom\u00e0quet Sec Provolone\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lasmuns.com\/ca\/#website\",\"url\":\"https:\/\/lasmuns.com\/ca\/\",\"name\":\"Las Muns\",\"description\":\"The &#039;Heart-Made&#039; Empanada\",\"publisher\":{\"@id\":\"https:\/\/lasmuns.com\/ca\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lasmuns.com\/ca\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/lasmuns.com\/ca\/#organization\",\"name\":\"Las Muns\",\"url\":\"https:\/\/lasmuns.com\/ca\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\/\/lasmuns.com\/ca\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/isologo-slogan2.svg\",\"contentUrl\":\"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/isologo-slogan2.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"Las Muns\"},\"image\":{\"@id\":\"https:\/\/lasmuns.com\/ca\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/lasmuns\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tom\u00e0quet Sec Provolone - Las Muns","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasmuns.com\/ca\/carta\/empanades-ca\/todos\/tomaquet-sec-provolone\/","og_locale":"ca_ES","og_type":"article","og_title":"Tom\u00e0quet Sec Provolone - Las Muns","og_description":"Tom\u00e0quets semisecs italians, provolone D.O.P., mozzarella 100% i orenga. El sabor de la bella It\u00e0lia.","og_url":"https:\/\/lasmuns.com\/ca\/carta\/empanades-ca\/todos\/tomaquet-sec-provolone\/","og_site_name":"Las Muns","article_modified_time":"2026-06-11T13:37:39+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lasmuns.com\/ca\/carta\/empanades-ca\/todos\/tomaquet-sec-provolone\/","url":"https:\/\/lasmuns.com\/ca\/carta\/empanades-ca\/todos\/tomaquet-sec-provolone\/","name":"Tom\u00e0quet Sec Provolone - Las Muns","isPartOf":{"@id":"https:\/\/lasmuns.com\/ca\/#website"},"datePublished":"2022-07-04T11:09:37+00:00","dateModified":"2026-06-11T13:37:39+00:00","breadcrumb":{"@id":"https:\/\/lasmuns.com\/ca\/carta\/empanades-ca\/todos\/tomaquet-sec-provolone\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasmuns.com\/ca\/carta\/empanades-ca\/todos\/tomaquet-sec-provolone\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lasmuns.com\/ca\/carta\/empanades-ca\/todos\/tomaquet-sec-provolone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lasmuns.com\/ca\/pagina-ejemplo\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/lasmuns.com\/ca\/carta\/%tipo%\/%subtipo%\/"},{"@type":"ListItem","position":3,"name":"Tom\u00e0quet Sec Provolone"}]},{"@type":"WebSite","@id":"https:\/\/lasmuns.com\/ca\/#website","url":"https:\/\/lasmuns.com\/ca\/","name":"Las Muns","description":"The &#039;Heart-Made&#039; Empanada","publisher":{"@id":"https:\/\/lasmuns.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasmuns.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/lasmuns.com\/ca\/#organization","name":"Las Muns","url":"https:\/\/lasmuns.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/lasmuns.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/isologo-slogan2.svg","contentUrl":"https:\/\/lasmuns.com\/wp-content\/uploads\/2022\/06\/isologo-slogan2.svg","width":"1024","height":"1024","caption":"Las Muns"},"image":{"@id":"https:\/\/lasmuns.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/lasmuns"]}]}},"_links":{"self":[{"href":"https:\/\/lasmuns.com\/ca\/wp-json\/wp\/v2\/productos\/3167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasmuns.com\/ca\/wp-json\/wp\/v2\/productos"}],"about":[{"href":"https:\/\/lasmuns.com\/ca\/wp-json\/wp\/v2\/types\/productos"}],"wp:attachment":[{"href":"https:\/\/lasmuns.com\/ca\/wp-json\/wp\/v2\/media?parent=3167"}],"wp:term":[{"taxonomy":"tipos","embeddable":true,"href":"https:\/\/lasmuns.com\/ca\/wp-json\/wp\/v2\/tipos?post=3167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}